{"id":63752,"date":"2017-10-10T12:45:18","date_gmt":"2017-10-10T10:45:18","guid":{"rendered":"https:\/\/www.weitzer-parkett.com\/warum-weitzer-parkett\/parkett-referenzen\/mcdonalds-mccafe\/"},"modified":"2025-09-16T09:51:38","modified_gmt":"2025-09-16T07:51:38","slug":"mcdonalds-mccafe","status":"publish","type":"referenz","link":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/mcdonalds-mccafe\/","title":{"rendered":"McDonalds &#8211; McCaf\u00e9"},"content":{"rendered":"<div id=\"ep-block-page-header-block_d54cb56e050455f2735ffeca253a4113\" class=\"ep-block-page-header ep-block  chosen-bg-theme-beige type-2\">\n            <div class=\"show-frontend\">\n\n            \n                <div class=\"inner\">\n                    <div class=\"container mx-auto\">\n                        <div class=\"text-container\">\n\n                                                            <div class=\"breadcrumbs-wrapper\">\n                                    <span><span><a href=\"https:\/\/www.weitzer-parkett.com\/fr\/\">Home<\/a><\/span><\/span>\n                                <\/div>\n                            \n                                                            <h1>McDonald&#8217;s &#8211; McCaf\u00e9<\/h1>\n                            \n                                                            <div class=\"text-wrapper\"><p>Les McCaf\u00e9s de McDonald&#8217;s b\u00e9n\u00e9ficient actuellement d&#8217;un relooking int\u00e9ressant. Une \u00e9l\u00e9gance intemporelle alli\u00e9e \u00e0 une touche urbaine dans l&#8217;am\u00e9nagement invite \u00e0 savourer un caf\u00e9 et un g\u00e2teau.<\/p>\n<\/div>\n                            \n                            \n                        <\/div>\n                    <\/div>\n                <\/div>\n\n                                                        <div class=\"image-wrapper\">\n                        \n                        \n                        \n                                                                                                        \n                        \n                                                                        \n                        <picture class=\"image\">\n                            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/02_McCafe-910x666-c-center.jpg 1x\" media=\"(min-resolution: 120dpi)\"\/>\n                            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/02_McCafe-910x666-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n                            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/02_McCafe-684x496-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n                            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/02_McCafe-356x258-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n                            <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/02_McCafe-356x258-c-center.jpg\" alt=\"\" title=\"02_McCafe.jpg\"\/>\n                        <\/picture>\n                    <\/div>\n\n                                    \n                    <\/div>\n    <\/div>\n\n\n<div id=\"ep-block-wysiwyg-block_49abc04b07f91726a102924396750ec6\" class=\"ep-block-wysiwyg ep-block  chosen-bg-white\">\n                        <div class=\"show-frontend\">\n                <div class=\"inner\">\n                    <div class=\"holder\"><p>L&#8217;am\u00e9nagement utilise des mat\u00e9riaux authentiques tels que le bois et le cuir. Des tons pastel doux rendent les nouveaux McCaf\u00e9s vraiment confortables. Nous avons \u00e9galement particip\u00e9 en r\u00e9alisant un parquet qui joue parfaitement avec une touche de couleur. La pose en tresse \u00e0 quatre brins n&#8217;est pas enchev\u00eatr\u00e9e, mais au contraire, dynamis\u00e9e avec des lames individuelles en pastel. La surface du parquet sain a \u00e9t\u00e9 trait\u00e9e avec des huiles pures et naturelles, offrant une protection sp\u00e9ciale au parquet. Ainsi, le parquet avec une touche de couleur r\u00e9siste longtemps.<\/p>\n<p>Entreprises ex\u00e9cutantes :<br \/>\n<a href=\"https:\/\/www.weitzer-parkett.com\/fr\/showroom\/boden-karner-gmbh-2\/\">Boden Karner GmbH, St. P\u00f6lten<\/a><br \/>\n<a href=\"https:\/\/www.weitzer-parkett.com\/fr\/showroom\/gager-gmbh\/\">Gager GmbH, Lockenhaus<\/a><br \/>\nZach B\u00f6den GmbH, Graz<\/p>\n<\/div>\n                <\/div>\n            <\/div>\n            <\/div>\n\n<div id=\"ep-block-gallery-block_f14b5a448327d3fdd99d88f3abebdd0e\" class=\"ep-block-gallery ep-block  chosen-\">\n                        <div class=\"show-frontend\">\n                <a href=\"#\" class=\"slick-prev-next slick-prev\">\n                    <svg id=\"f98cebba-e5ca-4a5b-a9d2-8a8f4b718c48\" data-name=\"Ebene 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 66.5 66.5\">\n  <defs>\n    <style>\n      .ab78e223-9e67-4f7d-821d-36fa53b307a7 {\n        fill: #281212;\n      }\n    <\/style>\n  <\/defs>\n  <path class=\"ab78e223-9e67-4f7d-821d-36fa53b307a7\" d=\"M.25,33.5A33.25,33.25,0,1,1,33.5,66.75,33.29,33.29,0,0,1,.25,33.5Zm1.5,0A31.75,31.75,0,1,0,33.5,1.75,31.78,31.78,0,0,0,1.75,33.5Z\" transform=\"translate(-0.25 -0.25)\"\/>\n  <polygon class=\"ab78e223-9e67-4f7d-821d-36fa53b307a7\" points=\"38.81 50.27 39.88 49.23 24.14 33.1 39.88 16.97 38.81 15.92 22.05 33.1 38.81 50.27\"\/>\n<\/svg>\n                <\/a>\n\n                <div class=\"gallery-wrapper\">\n                    <div class=\"slider\">\n                                                    <div class=\"slide-item\">\n                                                                                                                                                                                                                                                        \n\n                                                                        \n                                                                        \n                                    <picture class=\"image is-landscape\">\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/16_McCafe-820x540-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/16_McCafe-820x540-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/16_McCafe-430x288-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/16_McCafe-430x288-c-center.jpg\" class=\"no-lazy\" alt=\"\" title=\"16_McCafe.jpg\"\/>\n                                                                            <\/picture>\n                                                            <\/div>\n                                                    <div class=\"slide-item\">\n                                                                                                                                                                                                                                                        \n\n                                                                        \n                                                                        \n                                    <picture class=\"image is-landscape\">\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/15_McCafe-820x540-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/15_McCafe-820x540-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/15_McCafe-430x288-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/15_McCafe-430x288-c-center.jpg\" class=\"no-lazy\" alt=\"\" title=\"15_McCafe.jpg\"\/>\n                                                                            <\/picture>\n                                                            <\/div>\n                                                    <div class=\"slide-item\">\n                                                                                                                                                                                                                                                        \n\n                                                                        \n                                                                        \n                                    <picture class=\"image is-landscape\">\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/14_McCafe-820x540-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/14_McCafe-820x540-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/14_McCafe-430x288-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/14_McCafe-430x288-c-center.jpg\" class=\"no-lazy\" alt=\"\" title=\"14_McCafe.jpg\"\/>\n                                                                            <\/picture>\n                                                            <\/div>\n                                                    <div class=\"slide-item\">\n                                                                                                                                                                                                                                                        \n\n                                                                        \n                                                                        \n                                    <picture class=\"image is-landscape\">\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/13_McCafe-820x540-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/13_McCafe-820x540-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/13_McCafe-430x288-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/13_McCafe-430x288-c-center.jpg\" class=\"no-lazy\" alt=\"\" title=\"13_McCafe.jpg\"\/>\n                                                                            <\/picture>\n                                                            <\/div>\n                                                    <div class=\"slide-item\">\n                                                                                                                                                                                                                                                        \n\n                                                                        \n                                                                        \n                                    <picture class=\"image is-landscape\">\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/12_McCafe-820x540-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/12_McCafe-820x540-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/12_McCafe-430x288-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/12_McCafe-430x288-c-center.jpg\" class=\"no-lazy\" alt=\"\" title=\"12_McCafe.jpg\"\/>\n                                                                            <\/picture>\n                                                            <\/div>\n                                                    <div class=\"slide-item\">\n                                                                                                                                                                                                                                                        \n\n                                                                        \n                                                                        \n                                    <picture class=\"image is-landscape\">\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/06_McCafe-820x540-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/06_McCafe-820x540-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/06_McCafe-430x288-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/06_McCafe-430x288-c-center.jpg\" class=\"no-lazy\" alt=\"\" title=\"06_McCafe.jpg\"\/>\n                                                                            <\/picture>\n                                                            <\/div>\n                                                    <div class=\"slide-item\">\n                                                                                                                                                                                                                                                        \n\n                                                                        \n                                                                        \n                                    <picture class=\"image is-landscape\">\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_McCafe-820x540-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_McCafe-820x540-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_McCafe-430x288-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_McCafe-430x288-c-center.jpg\" class=\"no-lazy\" alt=\"\" title=\"01_McCafe.jpg\"\/>\n                                                                            <\/picture>\n                                                            <\/div>\n                                                    <div class=\"slide-item\">\n                                                                                                                                                                                                                                                        \n\n                                                                        \n                                                                        \n                                    <picture class=\"image is-landscape\">\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/10_McCafe-820x540-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/10_McCafe-820x540-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/10_McCafe-430x288-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/10_McCafe-430x288-c-center.jpg\" class=\"no-lazy\" alt=\"\" title=\"10_McCafe.jpg\"\/>\n                                                                            <\/picture>\n                                                            <\/div>\n                                            <\/div>\n                <\/div>\n\n                <a href=\"#\" class=\"slick-prev-next slick-next\">\n                    <svg id=\"ff25ce8b-1672-443b-9964-b93df5f1a4ba\" data-name=\"Ebene 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 66.5 66.5\">\n  <defs>\n    <style>\n      .eecbd091-678c-45b8-a12a-4b24f9fcaf43 {\n        fill: #281212;\n      }\n    <\/style>\n  <\/defs>\n  <path class=\"eecbd091-678c-45b8-a12a-4b24f9fcaf43\" d=\"M33.5,66.75A33.25,33.25,0,1,1,66.75,33.5,33.29,33.29,0,0,1,33.5,66.75Zm0-65A31.75,31.75,0,1,0,65.25,33.5,31.78,31.78,0,0,0,33.5,1.75Z\" transform=\"translate(-0.25 -0.25)\"\/>\n  <polygon class=\"eecbd091-678c-45b8-a12a-4b24f9fcaf43\" points=\"27.69 50.27 26.62 49.23 42.36 33.1 26.62 16.97 27.69 15.92 44.45 33.1 27.69 50.27\"\/>\n<\/svg>\n                <\/a>\n            <\/div>\n            <\/div>\n\n<div id=\"ep-block-button-block_fafccb79c365272c9b75eb319fe3deeb\" class=\"ep-block-button ep-block  chosen-bg-white\">\n                        <div class=\"show-frontend\">\n                <div class=\"holder\">\n                    <div class=\"button-wrapper content-center\">\n                        <a href=\"https:\/\/www.weitzer-parkett.com\/fr\/parquet\/\" target=\"\" class=\"btn standard arrow-right\">\n                            trouver un produit similaire\n                        <\/a>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <\/div>\n\n<div id=\"ep-block-related-block_012652316278bca37eb47f18af9efd95\" class=\"ep-block-related ep-block  chosen-bg-white\">\n                            <div class=\"ep-boxed-list mobile-slider shortcode-related\">\n        <div class=\"show-frontend\">\n                            <h2>Autres r\u00e9f\u00e9rences de Weitzer Parquet<\/h2>\n            \n            <div class=\"holder\">\n    <div class=\"boxed-items-wrapper\">\n        <div class=\"slider\">\n                            <div class=\"box-item\">\n                    <div class=\"box-inner\">\n                        <div class=\"box-header\">\n                    \n                        \n        <picture class=\"image\">\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_buero-am-opernring-276x197-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_buero-am-opernring-552x394-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_buero-am-opernring-552x394-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n            <a href=\"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/buero-am-opernring\/\">\n                <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_buero-am-opernring-552x394-c-center.jpg\" alt=\"\" title=\"01_buero-am-opernring.jpg\"\/>\n            <\/a>\n        <\/picture>\n    <\/div>                        <div class=\"box-body\">\n    <h3>\n        <a href=\"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/buero-am-opernring\/\">\n            Bureaux \u00e0 Opernring\n\n                    <\/a>\n    <\/h3>\n<\/div>\n                        <div class=\"box-footer referenz\">\n    <div class=\"col-1\">\n                    <span class=\"icon\">\n                <svg id=\"a5119c8a-4c42-4c55-916b-4cbfcecb3941\" data-name=\"Ebene 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 10.36 15.93\">\n  <defs>\n    <style>\n      .bc3bc798-26a7-4da0-b9be-31151b056cd3 {\n        fill: #94848f;\n      }\n    <\/style>\n  <\/defs>\n  <path class=\"bc3bc798-26a7-4da0-b9be-31151b056cd3\" d=\"M5.28,16.09a.54.54,0,0,1-.45-.25C4.63,15.53.1,8.34.1,5.54a5.49,5.49,0,0,1,1.51-3.8A5.05,5.05,0,0,1,9,1.74a5.47,5.47,0,0,1,1.51,3.8c0,2.8-4.53,10-4.73,10.3A.54.54,0,0,1,5.28,16.09Zm0-14.86a4,4,0,0,0-2.9,1.26A4.47,4.47,0,0,0,1.17,5.54c0,1.85,2.65,6.58,4.11,9,1.46-2.41,4.1-7.14,4.1-9a4.46,4.46,0,0,0-1.2-3A4,4,0,0,0,5.28,1.23Z\" transform=\"translate(-0.1 -0.16)\"\/>\n  <path class=\"bc3bc798-26a7-4da0-b9be-31151b056cd3\" d=\"M5.28,8.09A2.83,2.83,0,1,1,8.14,5.27,2.84,2.84,0,0,1,5.28,8.09Zm0-4.57A1.75,1.75,0,1,0,7.06,5.27,1.76,1.76,0,0,0,5.28,3.52Z\" transform=\"translate(-0.1 -0.16)\"\/>\n<\/svg>\n            <\/span>\n            <span class=\"value\">Vienne, <\/br>Autriche<\/span>\n            <\/div>\n    <div class=\"col-2\">\n                    <span class=\"value\">740 m2<\/span>\n            <\/div>\n<\/div>\n                    <\/div>\n                <\/div>\n                            <div class=\"box-item\">\n                    <div class=\"box-inner\">\n                        <div class=\"box-header\">\n                    \n                        \n        <picture class=\"image\">\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/mitten-im-zweiten-1-276x197-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/mitten-im-zweiten-1-552x394-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/mitten-im-zweiten-1-552x394-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n            <a href=\"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/vivre-au-coeur-du-deuxieme\/\">\n                <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/mitten-im-zweiten-1-552x394-c-center.jpg\" alt=\"\" title=\"mitten-im-zweiten-1.jpg\"\/>\n            <\/a>\n        <\/picture>\n    <\/div>                        <div class=\"box-body\">\n    <h3>\n        <a href=\"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/vivre-au-coeur-du-deuxieme\/\">\n            Au milieu du deuxi\u00e8me arrondissement\n\n                    <\/a>\n    <\/h3>\n<\/div>\n                        <div class=\"box-footer referenz\">\n    <div class=\"col-1\">\n                    <span class=\"icon\">\n                <svg id=\"a5119c8a-4c42-4c55-916b-4cbfcecb3941\" data-name=\"Ebene 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 10.36 15.93\">\n  <defs>\n    <style>\n      .bc3bc798-26a7-4da0-b9be-31151b056cd3 {\n        fill: #94848f;\n      }\n    <\/style>\n  <\/defs>\n  <path class=\"bc3bc798-26a7-4da0-b9be-31151b056cd3\" d=\"M5.28,16.09a.54.54,0,0,1-.45-.25C4.63,15.53.1,8.34.1,5.54a5.49,5.49,0,0,1,1.51-3.8A5.05,5.05,0,0,1,9,1.74a5.47,5.47,0,0,1,1.51,3.8c0,2.8-4.53,10-4.73,10.3A.54.54,0,0,1,5.28,16.09Zm0-14.86a4,4,0,0,0-2.9,1.26A4.47,4.47,0,0,0,1.17,5.54c0,1.85,2.65,6.58,4.11,9,1.46-2.41,4.1-7.14,4.1-9a4.46,4.46,0,0,0-1.2-3A4,4,0,0,0,5.28,1.23Z\" transform=\"translate(-0.1 -0.16)\"\/>\n  <path class=\"bc3bc798-26a7-4da0-b9be-31151b056cd3\" d=\"M5.28,8.09A2.83,2.83,0,1,1,8.14,5.27,2.84,2.84,0,0,1,5.28,8.09Zm0-4.57A1.75,1.75,0,1,0,7.06,5.27,1.76,1.76,0,0,0,5.28,3.52Z\" transform=\"translate(-0.1 -0.16)\"\/>\n<\/svg>\n            <\/span>\n            <span class=\"value\">1020 Vienne, <\/br>Autriche<\/span>\n            <\/div>\n    <div class=\"col-2\">\n            <\/div>\n<\/div>\n                    <\/div>\n                <\/div>\n                            <div class=\"box-item\">\n                    <div class=\"box-inner\">\n                        <div class=\"box-header\">\n                    \n                        \n        <picture class=\"image\">\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_TauernSpa-276x197-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_TauernSpa-552x394-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_TauernSpa-552x394-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n            <a href=\"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/tauern-spa\/\">\n                <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_TauernSpa-552x394-c-center.jpg\" alt=\"\" title=\"01_TauernSpa.jpg\"\/>\n            <\/a>\n        <\/picture>\n    <\/div>                        <div class=\"box-body\">\n    <h3>\n        <a href=\"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/tauern-spa\/\">\n            Tauern Spa\n\n                    <\/a>\n    <\/h3>\n<\/div>\n                        <div class=\"box-footer referenz\">\n    <div class=\"col-1\">\n                    <span class=\"icon\">\n                <svg id=\"a5119c8a-4c42-4c55-916b-4cbfcecb3941\" data-name=\"Ebene 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 10.36 15.93\">\n  <defs>\n    <style>\n      .bc3bc798-26a7-4da0-b9be-31151b056cd3 {\n        fill: #94848f;\n      }\n    <\/style>\n  <\/defs>\n  <path class=\"bc3bc798-26a7-4da0-b9be-31151b056cd3\" d=\"M5.28,16.09a.54.54,0,0,1-.45-.25C4.63,15.53.1,8.34.1,5.54a5.49,5.49,0,0,1,1.51-3.8A5.05,5.05,0,0,1,9,1.74a5.47,5.47,0,0,1,1.51,3.8c0,2.8-4.53,10-4.73,10.3A.54.54,0,0,1,5.28,16.09Zm0-14.86a4,4,0,0,0-2.9,1.26A4.47,4.47,0,0,0,1.17,5.54c0,1.85,2.65,6.58,4.11,9,1.46-2.41,4.1-7.14,4.1-9a4.46,4.46,0,0,0-1.2-3A4,4,0,0,0,5.28,1.23Z\" transform=\"translate(-0.1 -0.16)\"\/>\n  <path class=\"bc3bc798-26a7-4da0-b9be-31151b056cd3\" d=\"M5.28,8.09A2.83,2.83,0,1,1,8.14,5.27,2.84,2.84,0,0,1,5.28,8.09Zm0-4.57A1.75,1.75,0,1,0,7.06,5.27,1.76,1.76,0,0,0,5.28,3.52Z\" transform=\"translate(-0.1 -0.16)\"\/>\n<\/svg>\n            <\/span>\n            <span class=\"value\">Kaprun, <\/br>\u00d6sterreich<\/span>\n            <\/div>\n    <div class=\"col-2\">\n                    <span class=\"value\">8000 m2<\/span>\n            <\/div>\n<\/div>\n                    <\/div>\n                <\/div>\n                            <div class=\"box-item\">\n                    <div class=\"box-inner\">\n                        <div class=\"box-header\">\n                    \n                        \n        <picture class=\"image\">\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_Raiffeisen_Moedling-276x197-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_Raiffeisen_Moedling-552x394-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_Raiffeisen_Moedling-552x394-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n            <a href=\"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/raiffeisen-forum-moedling\/\">\n                <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_Raiffeisen_Moedling-552x394-c-center.jpg\" alt=\"\" title=\"01_Raiffeisen_Moedling.jpg\"\/>\n            <\/a>\n        <\/picture>\n    <\/div>                        <div class=\"box-body\">\n    <h3>\n        <a href=\"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/raiffeisen-forum-moedling\/\">\n            Raiffeisen Forum M\u00f6dling\n\n                    <\/a>\n    <\/h3>\n<\/div>\n                        <div class=\"box-footer referenz\">\n    <div class=\"col-1\">\n                    <span class=\"icon\">\n                <svg id=\"a5119c8a-4c42-4c55-916b-4cbfcecb3941\" data-name=\"Ebene 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 10.36 15.93\">\n  <defs>\n    <style>\n      .bc3bc798-26a7-4da0-b9be-31151b056cd3 {\n        fill: #94848f;\n      }\n    <\/style>\n  <\/defs>\n  <path class=\"bc3bc798-26a7-4da0-b9be-31151b056cd3\" d=\"M5.28,16.09a.54.54,0,0,1-.45-.25C4.63,15.53.1,8.34.1,5.54a5.49,5.49,0,0,1,1.51-3.8A5.05,5.05,0,0,1,9,1.74a5.47,5.47,0,0,1,1.51,3.8c0,2.8-4.53,10-4.73,10.3A.54.54,0,0,1,5.28,16.09Zm0-14.86a4,4,0,0,0-2.9,1.26A4.47,4.47,0,0,0,1.17,5.54c0,1.85,2.65,6.58,4.11,9,1.46-2.41,4.1-7.14,4.1-9a4.46,4.46,0,0,0-1.2-3A4,4,0,0,0,5.28,1.23Z\" transform=\"translate(-0.1 -0.16)\"\/>\n  <path class=\"bc3bc798-26a7-4da0-b9be-31151b056cd3\" d=\"M5.28,8.09A2.83,2.83,0,1,1,8.14,5.27,2.84,2.84,0,0,1,5.28,8.09Zm0-4.57A1.75,1.75,0,1,0,7.06,5.27,1.76,1.76,0,0,0,5.28,3.52Z\" transform=\"translate(-0.1 -0.16)\"\/>\n<\/svg>\n            <\/span>\n            <span class=\"value\">M\u00f6dling, <\/br>Autriche<\/span>\n            <\/div>\n    <div class=\"col-2\">\n                    <span class=\"value\">620 m2<\/span>\n            <\/div>\n<\/div>\n                    <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n                            <div class=\"link-wrapper\">\n                    <a href=\"https:\/\/www.weitzer-parkett.com\/fr\/references\/\" target=\"\" class=\"btn link arrow-right\">Voir toutes les r\u00e9f\u00e9rences<\/a>\n                <\/div>\n                    <\/div>\n    <\/div>\n\n            <\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":5649,"parent":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":true},"reference_category":[35],"class_list":["post-63752","referenz","type-referenz","status-publish","has-post-thumbnail","hentry","reference_category-hotellerie-restauration-wellness-fitness"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>McDonalds - McCaf\u00e9 | Weitzer Parkett<\/title>\n<meta name=\"description\" content=\"Parquet au McCaf\u00e9 \u2713 facile d\u2019entretien, moderne et chaleureux \u2192 apporte confort et style contemporain \u00e0 l\u2019espace.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/mcdonalds-mccafe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"McDonalds - McCaf\u00e9 | Weitzer Parkett\" \/>\n<meta property=\"og:description\" content=\"Parquet au McCaf\u00e9 \u2713 facile d\u2019entretien, moderne et chaleureux \u2192 apporte confort et style contemporain \u00e0 l\u2019espace.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/mcdonalds-mccafe\/\" \/>\n<meta property=\"og:site_name\" content=\"Weitzer Parkett\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/weitzerparkett\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-16T07:51:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_McCafe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"749\" \/>\n\t<meta property=\"og:image:height\" content=\"499\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@weitzerparkett\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/pourquoi-weitzer-parkett\\\/references\\\/mcdonalds-mccafe\\\/\",\"url\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/pourquoi-weitzer-parkett\\\/references\\\/mcdonalds-mccafe\\\/\",\"name\":\"McDonalds - McCaf\u00e9 | Weitzer Parkett\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/pourquoi-weitzer-parkett\\\/references\\\/mcdonalds-mccafe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/pourquoi-weitzer-parkett\\\/references\\\/mcdonalds-mccafe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/01_McCafe.jpg\",\"datePublished\":\"2017-10-10T10:45:18+00:00\",\"dateModified\":\"2025-09-16T07:51:38+00:00\",\"description\":\"Parquet au McCaf\u00e9 \u2713 facile d\u2019entretien, moderne et chaleureux \u2192 apporte confort et style contemporain \u00e0 l\u2019espace.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/pourquoi-weitzer-parkett\\\/references\\\/mcdonalds-mccafe\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/pourquoi-weitzer-parkett\\\/references\\\/mcdonalds-mccafe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/pourquoi-weitzer-parkett\\\/references\\\/mcdonalds-mccafe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/01_McCafe.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/01_McCafe.jpg\",\"width\":749,\"height\":499},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/pourquoi-weitzer-parkett\\\/references\\\/mcdonalds-mccafe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9f\u00e9rence\",\"item\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/pourquoi-weitzer-parkett\\\/references\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"McDonalds &#8211; McCaf\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/\",\"name\":\"Weitzer Parkett\",\"description\":\"Intelligente Parkett- und Stiegenl\u00f6sungen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/#organization\",\"name\":\"Weitzer Parkett\",\"url\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/weitzer-parkett-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/weitzer-parkett-logo.png\",\"width\":253,\"height\":81,\"caption\":\"Weitzer Parkett\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/weitzerparkett\",\"https:\\\/\\\/x.com\\\/weitzerparkett\",\"http:\\\/\\\/www.linkedin.com\\\/company\\\/weitzer-parkett\",\"https:\\\/\\\/www.pinterest.com\\\/weitzerparkett\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/weitzerparkett\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"McDonalds - McCaf\u00e9 | Weitzer Parkett","description":"Parquet au McCaf\u00e9 \u2713 facile d\u2019entretien, moderne et chaleureux \u2192 apporte confort et style contemporain \u00e0 l\u2019espace.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/mcdonalds-mccafe\/","og_locale":"fr_FR","og_type":"article","og_title":"McDonalds - McCaf\u00e9 | Weitzer Parkett","og_description":"Parquet au McCaf\u00e9 \u2713 facile d\u2019entretien, moderne et chaleureux \u2192 apporte confort et style contemporain \u00e0 l\u2019espace.","og_url":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/mcdonalds-mccafe\/","og_site_name":"Weitzer Parkett","article_publisher":"http:\/\/www.facebook.com\/weitzerparkett","article_modified_time":"2025-09-16T07:51:38+00:00","og_image":[{"width":749,"height":499,"url":"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_McCafe.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@weitzerparkett","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/mcdonalds-mccafe\/","url":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/mcdonalds-mccafe\/","name":"McDonalds - McCaf\u00e9 | Weitzer Parkett","isPartOf":{"@id":"https:\/\/www.weitzer-parkett.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/mcdonalds-mccafe\/#primaryimage"},"image":{"@id":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/mcdonalds-mccafe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_McCafe.jpg","datePublished":"2017-10-10T10:45:18+00:00","dateModified":"2025-09-16T07:51:38+00:00","description":"Parquet au McCaf\u00e9 \u2713 facile d\u2019entretien, moderne et chaleureux \u2192 apporte confort et style contemporain \u00e0 l\u2019espace.","breadcrumb":{"@id":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/mcdonalds-mccafe\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/mcdonalds-mccafe\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/mcdonalds-mccafe\/#primaryimage","url":"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_McCafe.jpg","contentUrl":"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_McCafe.jpg","width":749,"height":499},{"@type":"BreadcrumbList","@id":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/mcdonalds-mccafe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.weitzer-parkett.com\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e9f\u00e9rence","item":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/"},{"@type":"ListItem","position":3,"name":"McDonalds &#8211; McCaf\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.weitzer-parkett.com\/fr\/#website","url":"https:\/\/www.weitzer-parkett.com\/fr\/","name":"Weitzer Parkett","description":"Intelligente Parkett- und Stiegenl\u00f6sungen","publisher":{"@id":"https:\/\/www.weitzer-parkett.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weitzer-parkett.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.weitzer-parkett.com\/fr\/#organization","name":"Weitzer Parkett","url":"https:\/\/www.weitzer-parkett.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.weitzer-parkett.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2018\/01\/weitzer-parkett-logo.png","contentUrl":"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2018\/01\/weitzer-parkett-logo.png","width":253,"height":81,"caption":"Weitzer Parkett"},"image":{"@id":"https:\/\/www.weitzer-parkett.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/weitzerparkett","https:\/\/x.com\/weitzerparkett","http:\/\/www.linkedin.com\/company\/weitzer-parkett","https:\/\/www.pinterest.com\/weitzerparkett\/","https:\/\/www.youtube.com\/user\/weitzerparkett\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.weitzer-parkett.com\/fr\/wp-json\/wp\/v2\/referenz\/63752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weitzer-parkett.com\/fr\/wp-json\/wp\/v2\/referenz"}],"about":[{"href":"https:\/\/www.weitzer-parkett.com\/fr\/wp-json\/wp\/v2\/types\/referenz"}],"author":[{"embeddable":true,"href":"https:\/\/www.weitzer-parkett.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weitzer-parkett.com\/fr\/wp-json\/wp\/v2\/comments?post=63752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weitzer-parkett.com\/fr\/wp-json\/wp\/v2\/media\/5649"}],"wp:attachment":[{"href":"https:\/\/www.weitzer-parkett.com\/fr\/wp-json\/wp\/v2\/media?parent=63752"}],"wp:term":[{"taxonomy":"reference_category","embeddable":true,"href":"https:\/\/www.weitzer-parkett.com\/fr\/wp-json\/wp\/v2\/reference_category?post=63752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}