{"id":17500,"date":"2017-10-10T12:45:18","date_gmt":"2017-10-10T10:45:18","guid":{"rendered":"https:\/\/www.weitzer-parkett.com\/warum-weitzer-parkett\/parkett-referenzen\/pavillon-salvesen\/"},"modified":"2025-05-13T13:52:11","modified_gmt":"2025-05-13T11:52:11","slug":"privathaus-henriette-salvesen","status":"publish","type":"referenz","link":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/privathaus-henriette-salvesen\/","title":{"rendered":"Pavillon Henriette Salvesen"},"content":{"rendered":"<div id=\"ep-block-page-header-block_624b0a0fe5e6b\" class=\"ep-block-page-header ep-block  chosen-bg-theme-beige type-2\">\n            <div class=\"show-frontend\">\n\n            \n                <div class=\"inner\">\n                    <div class=\"container mx-auto\">\n                        <div class=\"text-container\">\n\n                                                            <div class=\"breadcrumbs-wrapper\">\n                                    <span><span><a href=\"https:\/\/www.weitzer-parkett.com\/fr\/\">Home<\/a><\/span><\/span>\n                                <\/div>\n                            \n                                                            <h1>Pavillon Henriette Salvesen<\/h1>\n                            \n                            \n                            \n                        <\/div>\n                    <\/div>\n                <\/div>\n\n                                                        <div class=\"image-wrapper\">\n                        \n                        \n                        \n                                                                                                        \n                        \n                                                                        \n                        <picture class=\"image\">\n                            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_privathaus-salvesen-910x666-c-center.jpg 1x\" media=\"(min-resolution: 120dpi)\"\/>\n                            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_privathaus-salvesen-910x666-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n                            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_privathaus-salvesen-684x496-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n                            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_privathaus-salvesen-356x258-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n                            <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_privathaus-salvesen-356x258-c-center.jpg\" alt=\"\" title=\"01_privathaus-salvesen.jpg\"\/>\n                        <\/picture>\n                    <\/div>\n\n                                    \n                    <\/div>\n    <\/div>\n\n\n<div id=\"ep-block-wysiwyg-block_6242c0a86268c\" class=\"ep-block-wysiwyg ep-block  chosen-bg-white\">\n                        <div class=\"show-frontend\">\n                <div class=\"inner\">\n                    <div class=\"holder\"><p>Project realisation: ProsjektGulv AS, Stokke<\/p>\n<\/div>\n                <\/div>\n            <\/div>\n            <\/div>\n\n<div id=\"ep-block-gallery-block_6242c0ab6268d\" class=\"ep-block-gallery ep-block  chosen-bg-white\">\n                        <div class=\"show-frontend\">\n                <a href=\"#\" class=\"slick-prev-next slick-prev\">\n                    <svg id=\"f98cebba-e5ca-4a5b-a9d2-8a8f4b718c48\" data-name=\"Ebene 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 66.5 66.5\">\n  <defs>\n    <style>\n      .ab78e223-9e67-4f7d-821d-36fa53b307a7 {\n        fill: #281212;\n      }\n    <\/style>\n  <\/defs>\n  <path class=\"ab78e223-9e67-4f7d-821d-36fa53b307a7\" d=\"M.25,33.5A33.25,33.25,0,1,1,33.5,66.75,33.29,33.29,0,0,1,.25,33.5Zm1.5,0A31.75,31.75,0,1,0,33.5,1.75,31.78,31.78,0,0,0,1.75,33.5Z\" transform=\"translate(-0.25 -0.25)\"\/>\n  <polygon class=\"ab78e223-9e67-4f7d-821d-36fa53b307a7\" points=\"38.81 50.27 39.88 49.23 24.14 33.1 39.88 16.97 38.81 15.92 22.05 33.1 38.81 50.27\"\/>\n<\/svg>\n                <\/a>\n\n                <div class=\"gallery-wrapper\">\n                    <div class=\"slider\">\n                                                    <div class=\"slide-item\">\n                                                                                                                                                                                                                                                        \n\n                                                                        \n                                                                        \n                                    <picture class=\"image is-landscape\">\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2020\/09\/privathaus-salvesen-wohnraum-holzboden-820x540-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2020\/09\/privathaus-salvesen-wohnraum-holzboden-820x540-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2020\/09\/privathaus-salvesen-wohnraum-holzboden-430x288-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2020\/09\/privathaus-salvesen-wohnraum-holzboden-430x288-c-center.jpg\" class=\"no-lazy\" alt=\"\" title=\"privathaus-salvesen-wohnraum-holzboden\"\/>\n                                                                            <\/picture>\n                                                            <\/div>\n                                                    <div class=\"slide-item\">\n                                                                                                                                                                                                                                                        \n\n                                                                        \n                                                                        \n                                    <picture class=\"image is-landscape\">\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2020\/09\/privathaus-salvesen-leseecke-holzboden-820x540-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2020\/09\/privathaus-salvesen-leseecke-holzboden-820x540-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2020\/09\/privathaus-salvesen-leseecke-holzboden-430x288-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2020\/09\/privathaus-salvesen-leseecke-holzboden-430x288-c-center.jpg\" class=\"no-lazy\" alt=\"\" title=\"privathaus-salvesen-leseecke-holzboden\"\/>\n                                                                            <\/picture>\n                                                            <\/div>\n                                                    <div class=\"slide-item\">\n                                                                                                                                                                                                                                                        \n\n                                                                        \n                                                                        \n                                    <picture class=\"image is-landscape\">\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2020\/09\/privathaus-salvesen-kueche-holzboden-820x540-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2020\/09\/privathaus-salvesen-kueche-holzboden-820x540-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2020\/09\/privathaus-salvesen-kueche-holzboden-430x288-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2020\/09\/privathaus-salvesen-kueche-holzboden-430x288-c-center.jpg\" class=\"no-lazy\" alt=\"\" title=\"privathaus-salvesen-kueche-holzboden\"\/>\n                                                                            <\/picture>\n                                                            <\/div>\n                                                    <div class=\"slide-item\">\n                                                                                                                                                                                                                                                        \n\n                                                                        \n                                                                        \n                                    <picture class=\"image is-landscape\">\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2020\/09\/privathaus-salvesen-fitness-holzboden-820x540-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2020\/09\/privathaus-salvesen-fitness-holzboden-820x540-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2020\/09\/privathaus-salvesen-fitness-holzboden-430x288-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2020\/09\/privathaus-salvesen-fitness-holzboden-430x288-c-center.jpg\" class=\"no-lazy\" alt=\"\" title=\"privathaus-salvesen-fitness-holzboden\"\/>\n                                                                            <\/picture>\n                                                            <\/div>\n                                                    <div class=\"slide-item\">\n                                                                                                                                                                                                                                                        \n\n                                                                        \n                                                                        \n                                    <picture class=\"image is-landscape\">\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2020\/09\/privathaus-salvesen-esszimmer-holzboden-820x540-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2020\/09\/privathaus-salvesen-esszimmer-holzboden-820x540-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2020\/09\/privathaus-salvesen-esszimmer-holzboden-430x288-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2020\/09\/privathaus-salvesen-esszimmer-holzboden-430x288-c-center.jpg\" class=\"no-lazy\" alt=\"\" title=\"privathaus-salvesen-esszimmer-holzboden\"\/>\n                                                                            <\/picture>\n                                                            <\/div>\n                                                    <div class=\"slide-item\">\n                                                                                                                                                                                                                                                        \n\n                                                                        \n                                                                        \n                                    <picture class=\"image is-landscape\">\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_privathaus-salvesen-820x540-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_privathaus-salvesen-820x540-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n                                        <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_privathaus-salvesen-430x288-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_privathaus-salvesen-430x288-c-center.jpg\" class=\"no-lazy\" alt=\"\" title=\"01_privathaus-salvesen.jpg\"\/>\n                                                                            <\/picture>\n                                                            <\/div>\n                                            <\/div>\n                <\/div>\n\n                <a href=\"#\" class=\"slick-prev-next slick-next\">\n                    <svg id=\"ff25ce8b-1672-443b-9964-b93df5f1a4ba\" data-name=\"Ebene 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 66.5 66.5\">\n  <defs>\n    <style>\n      .eecbd091-678c-45b8-a12a-4b24f9fcaf43 {\n        fill: #281212;\n      }\n    <\/style>\n  <\/defs>\n  <path class=\"eecbd091-678c-45b8-a12a-4b24f9fcaf43\" d=\"M33.5,66.75A33.25,33.25,0,1,1,66.75,33.5,33.29,33.29,0,0,1,33.5,66.75Zm0-65A31.75,31.75,0,1,0,65.25,33.5,31.78,31.78,0,0,0,33.5,1.75Z\" transform=\"translate(-0.25 -0.25)\"\/>\n  <polygon class=\"eecbd091-678c-45b8-a12a-4b24f9fcaf43\" points=\"27.69 50.27 26.62 49.23 42.36 33.1 26.62 16.97 27.69 15.92 44.45 33.1 27.69 50.27\"\/>\n<\/svg>\n                <\/a>\n            <\/div>\n            <\/div>\n\n<div id=\"ep-block-button-block_6242c0b36268e\" class=\"ep-block-button ep-block  chosen-bg-white\">\n                        <div class=\"show-frontend\">\n                <div class=\"holder\">\n                    <div class=\"button-wrapper content-center\">\n                        <a href=\"https:\/\/www.weitzer-parkett.com\/fr\/parquet\" target=\"\" class=\"btn standard arrow-right\">\n                            Trouver un produit similaire\n                        <\/a>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <\/div>\n\n<div id=\"ep-block-related-block_6242c0b86268f\" class=\"ep-block-related ep-block  chosen-bg-white\">\n                            <div class=\"ep-boxed-list mobile-slider shortcode-related\">\n        <div class=\"show-frontend\">\n                            <h2>Autres r\u00e9f\u00e9rences<\/h2>\n            \n            <div class=\"holder\">\n    <div class=\"boxed-items-wrapper\">\n        <div class=\"slider\">\n                            <div class=\"box-item\">\n                    <div class=\"box-inner\">\n                        <div class=\"box-header\">\n                    \n                        \n        <picture class=\"image\">\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_Kirche_Aldeanueva_Spanien-276x197-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_Kirche_Aldeanueva_Spanien-552x394-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_Kirche_Aldeanueva_Spanien-552x394-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n            <a href=\"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/kirche-aldeanueva-de-ebro\/\">\n                <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_Kirche_Aldeanueva_Spanien-552x394-c-center.jpg\" alt=\"\" title=\"wp_01_03\"\/>\n            <\/a>\n        <\/picture>\n    <\/div>                        <div class=\"box-body\">\n    <h3>\n        <a href=\"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/kirche-aldeanueva-de-ebro\/\">\n            Eglise Aldeanueva de Ebro\n\n                    <\/a>\n    <\/h3>\n<\/div>\n                        <div class=\"box-footer referenz\">\n    <div class=\"col-1\">\n                    <span class=\"icon\">\n                <svg id=\"a5119c8a-4c42-4c55-916b-4cbfcecb3941\" data-name=\"Ebene 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 10.36 15.93\">\n  <defs>\n    <style>\n      .bc3bc798-26a7-4da0-b9be-31151b056cd3 {\n        fill: #94848f;\n      }\n    <\/style>\n  <\/defs>\n  <path class=\"bc3bc798-26a7-4da0-b9be-31151b056cd3\" d=\"M5.28,16.09a.54.54,0,0,1-.45-.25C4.63,15.53.1,8.34.1,5.54a5.49,5.49,0,0,1,1.51-3.8A5.05,5.05,0,0,1,9,1.74a5.47,5.47,0,0,1,1.51,3.8c0,2.8-4.53,10-4.73,10.3A.54.54,0,0,1,5.28,16.09Zm0-14.86a4,4,0,0,0-2.9,1.26A4.47,4.47,0,0,0,1.17,5.54c0,1.85,2.65,6.58,4.11,9,1.46-2.41,4.1-7.14,4.1-9a4.46,4.46,0,0,0-1.2-3A4,4,0,0,0,5.28,1.23Z\" transform=\"translate(-0.1 -0.16)\"\/>\n  <path class=\"bc3bc798-26a7-4da0-b9be-31151b056cd3\" d=\"M5.28,8.09A2.83,2.83,0,1,1,8.14,5.27,2.84,2.84,0,0,1,5.28,8.09Zm0-4.57A1.75,1.75,0,1,0,7.06,5.27,1.76,1.76,0,0,0,5.28,3.52Z\" transform=\"translate(-0.1 -0.16)\"\/>\n<\/svg>\n            <\/span>\n            <span class=\"value\">Soria, <\/br>Espagne<\/span>\n            <\/div>\n    <div class=\"col-2\">\n                    <span class=\"value\">1200 m2<\/span>\n            <\/div>\n<\/div>\n                    <\/div>\n                <\/div>\n                            <div class=\"box-item\">\n                    <div class=\"box-inner\">\n                        <div class=\"box-header\">\n                    \n                        \n        <picture class=\"image\">\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/mitten-im-zweiten-1-276x197-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/mitten-im-zweiten-1-552x394-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/mitten-im-zweiten-1-552x394-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n            <a href=\"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/vivre-au-coeur-du-deuxieme\/\">\n                <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/mitten-im-zweiten-1-552x394-c-center.jpg\" alt=\"\" title=\"mitten-im-zweiten-1.jpg\"\/>\n            <\/a>\n        <\/picture>\n    <\/div>                        <div class=\"box-body\">\n    <h3>\n        <a href=\"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/vivre-au-coeur-du-deuxieme\/\">\n            Au milieu du deuxi\u00e8me arrondissement\n\n                    <\/a>\n    <\/h3>\n<\/div>\n                        <div class=\"box-footer referenz\">\n    <div class=\"col-1\">\n                    <span class=\"icon\">\n                <svg id=\"a5119c8a-4c42-4c55-916b-4cbfcecb3941\" data-name=\"Ebene 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 10.36 15.93\">\n  <defs>\n    <style>\n      .bc3bc798-26a7-4da0-b9be-31151b056cd3 {\n        fill: #94848f;\n      }\n    <\/style>\n  <\/defs>\n  <path class=\"bc3bc798-26a7-4da0-b9be-31151b056cd3\" d=\"M5.28,16.09a.54.54,0,0,1-.45-.25C4.63,15.53.1,8.34.1,5.54a5.49,5.49,0,0,1,1.51-3.8A5.05,5.05,0,0,1,9,1.74a5.47,5.47,0,0,1,1.51,3.8c0,2.8-4.53,10-4.73,10.3A.54.54,0,0,1,5.28,16.09Zm0-14.86a4,4,0,0,0-2.9,1.26A4.47,4.47,0,0,0,1.17,5.54c0,1.85,2.65,6.58,4.11,9,1.46-2.41,4.1-7.14,4.1-9a4.46,4.46,0,0,0-1.2-3A4,4,0,0,0,5.28,1.23Z\" transform=\"translate(-0.1 -0.16)\"\/>\n  <path class=\"bc3bc798-26a7-4da0-b9be-31151b056cd3\" d=\"M5.28,8.09A2.83,2.83,0,1,1,8.14,5.27,2.84,2.84,0,0,1,5.28,8.09Zm0-4.57A1.75,1.75,0,1,0,7.06,5.27,1.76,1.76,0,0,0,5.28,3.52Z\" transform=\"translate(-0.1 -0.16)\"\/>\n<\/svg>\n            <\/span>\n            <span class=\"value\">1020 Vienne, <\/br>Autriche<\/span>\n            <\/div>\n    <div class=\"col-2\">\n            <\/div>\n<\/div>\n                    <\/div>\n                <\/div>\n                            <div class=\"box-item\">\n                    <div class=\"box-inner\">\n                        <div class=\"box-header\">\n                    \n                        \n        <picture class=\"image\">\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2026\/02\/roots_final_4K-\u00a9Garbe-Immobilien-Projekte-Stoermer-Murphy-and-Partners_low-1-276x197-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2026\/02\/roots_final_4K-\u00a9Garbe-Immobilien-Projekte-Stoermer-Murphy-and-Partners_low-1-552x394-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2026\/02\/roots_final_4K-\u00a9Garbe-Immobilien-Projekte-Stoermer-Murphy-and-Partners_low-1-552x394-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n            <a href=\"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/roots-hamburg\/\">\n                <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2026\/02\/roots_final_4K-\u00a9Garbe-Immobilien-Projekte-Stoermer-Murphy-and-Partners_low-1-552x394-c-center.jpg\" alt=\"\" title=\"roots_final_4K-\u00a9Garbe-Immobilien-Projekte,-Sto\u0308rmer-Murphy-and-Partners_low-(1)\"\/>\n            <\/a>\n        <\/picture>\n    <\/div>                        <div class=\"box-body\">\n    <h3>\n        <a href=\"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/roots-hamburg\/\">\n            Roots Hamburg\n\n                    <\/a>\n    <\/h3>\n<\/div>\n                        <div class=\"box-footer referenz\">\n    <div class=\"col-1\">\n                    <span class=\"icon\">\n                <svg id=\"a5119c8a-4c42-4c55-916b-4cbfcecb3941\" data-name=\"Ebene 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 10.36 15.93\">\n  <defs>\n    <style>\n      .bc3bc798-26a7-4da0-b9be-31151b056cd3 {\n        fill: #94848f;\n      }\n    <\/style>\n  <\/defs>\n  <path class=\"bc3bc798-26a7-4da0-b9be-31151b056cd3\" d=\"M5.28,16.09a.54.54,0,0,1-.45-.25C4.63,15.53.1,8.34.1,5.54a5.49,5.49,0,0,1,1.51-3.8A5.05,5.05,0,0,1,9,1.74a5.47,5.47,0,0,1,1.51,3.8c0,2.8-4.53,10-4.73,10.3A.54.54,0,0,1,5.28,16.09Zm0-14.86a4,4,0,0,0-2.9,1.26A4.47,4.47,0,0,0,1.17,5.54c0,1.85,2.65,6.58,4.11,9,1.46-2.41,4.1-7.14,4.1-9a4.46,4.46,0,0,0-1.2-3A4,4,0,0,0,5.28,1.23Z\" transform=\"translate(-0.1 -0.16)\"\/>\n  <path class=\"bc3bc798-26a7-4da0-b9be-31151b056cd3\" d=\"M5.28,8.09A2.83,2.83,0,1,1,8.14,5.27,2.84,2.84,0,0,1,5.28,8.09Zm0-4.57A1.75,1.75,0,1,0,7.06,5.27,1.76,1.76,0,0,0,5.28,3.52Z\" transform=\"translate(-0.1 -0.16)\"\/>\n<\/svg>\n            <\/span>\n            <span class=\"value\">Hamburg, <\/br>Allemagne<\/span>\n            <\/div>\n    <div class=\"col-2\">\n                    <span class=\"value\">12.300 m2<\/span>\n            <\/div>\n<\/div>\n                    <\/div>\n                <\/div>\n                            <div class=\"box-item\">\n                    <div class=\"box-inner\">\n                        <div class=\"box-header\">\n                    \n                        \n        <picture class=\"image\">\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_Musikschule-Rohrbach-276x197-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_Musikschule-Rohrbach-552x394-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_Musikschule-Rohrbach-552x394-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n            <a href=\"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/musikschule-rohrbach\/\">\n                <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_Musikschule-Rohrbach-552x394-c-center.jpg\" alt=\"\" title=\"01_Musikschule-Rohrbach.jpg\"\/>\n            <\/a>\n        <\/picture>\n    <\/div>                        <div class=\"box-body\">\n    <h3>\n        <a href=\"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/musikschule-rohrbach\/\">\n            \u00c9cole Musique Rohrbach\n\n                    <\/a>\n    <\/h3>\n<\/div>\n                        <div class=\"box-footer referenz\">\n    <div class=\"col-1\">\n                    <span class=\"icon\">\n                <svg id=\"a5119c8a-4c42-4c55-916b-4cbfcecb3941\" data-name=\"Ebene 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 10.36 15.93\">\n  <defs>\n    <style>\n      .bc3bc798-26a7-4da0-b9be-31151b056cd3 {\n        fill: #94848f;\n      }\n    <\/style>\n  <\/defs>\n  <path class=\"bc3bc798-26a7-4da0-b9be-31151b056cd3\" d=\"M5.28,16.09a.54.54,0,0,1-.45-.25C4.63,15.53.1,8.34.1,5.54a5.49,5.49,0,0,1,1.51-3.8A5.05,5.05,0,0,1,9,1.74a5.47,5.47,0,0,1,1.51,3.8c0,2.8-4.53,10-4.73,10.3A.54.54,0,0,1,5.28,16.09Zm0-14.86a4,4,0,0,0-2.9,1.26A4.47,4.47,0,0,0,1.17,5.54c0,1.85,2.65,6.58,4.11,9,1.46-2.41,4.1-7.14,4.1-9a4.46,4.46,0,0,0-1.2-3A4,4,0,0,0,5.28,1.23Z\" transform=\"translate(-0.1 -0.16)\"\/>\n  <path class=\"bc3bc798-26a7-4da0-b9be-31151b056cd3\" d=\"M5.28,8.09A2.83,2.83,0,1,1,8.14,5.27,2.84,2.84,0,0,1,5.28,8.09Zm0-4.57A1.75,1.75,0,1,0,7.06,5.27,1.76,1.76,0,0,0,5.28,3.52Z\" transform=\"translate(-0.1 -0.16)\"\/>\n<\/svg>\n            <\/span>\n            <span class=\"value\">Rohrbach, <\/br>Autriche<\/span>\n            <\/div>\n    <div class=\"col-2\">\n                    <span class=\"value\">1600 m2<\/span>\n            <\/div>\n<\/div>\n                    <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n                            <div class=\"link-wrapper\">\n                    <a href=\"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\" target=\"\" class=\"btn link arrow-right\">\u00c0 l&#8217;aper\u00e7u<\/a>\n                <\/div>\n                    <\/div>\n    <\/div>\n\n            <\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":5576,"parent":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"reference_category":[31],"class_list":["post-17500","referenz","type-referenz","status-publish","has-post-thumbnail","hentry","reference_category-locaux-habitation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pavillon Henriette Salvesen | Weitzer Parkett<\/title>\n<meta name=\"description\" content=\"Le parquet Weitzer de la maison priv\u00e9e Salvesen allie design scandinave et durabilit\u00e9 : \u2713 le naturel \u2713 la fonctionnalit\u00e9 \u2713 l&#039;\u00e9l\u00e9gance intemporelle\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/privathaus-henriette-salvesen\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pavillon Henriette Salvesen | Weitzer Parkett\" \/>\n<meta property=\"og:description\" content=\"Le parquet Weitzer de la maison priv\u00e9e Salvesen allie design scandinave et durabilit\u00e9 : \u2713 le naturel \u2713 la fonctionnalit\u00e9 \u2713 l&#039;\u00e9l\u00e9gance intemporelle\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/privathaus-henriette-salvesen\/\" \/>\n<meta property=\"og:site_name\" content=\"Weitzer Parkett\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/weitzerparkett\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-13T11:52:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_privathaus-salvesen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@weitzerparkett\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/pourquoi-weitzer-parkett\\\/references\\\/privathaus-henriette-salvesen\\\/\",\"url\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/pourquoi-weitzer-parkett\\\/references\\\/privathaus-henriette-salvesen\\\/\",\"name\":\"Pavillon Henriette Salvesen | Weitzer Parkett\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/pourquoi-weitzer-parkett\\\/references\\\/privathaus-henriette-salvesen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/pourquoi-weitzer-parkett\\\/references\\\/privathaus-henriette-salvesen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/01_privathaus-salvesen.jpg\",\"datePublished\":\"2017-10-10T10:45:18+00:00\",\"dateModified\":\"2025-05-13T11:52:11+00:00\",\"description\":\"Le parquet Weitzer de la maison priv\u00e9e Salvesen allie design scandinave et durabilit\u00e9 : \u2713 le naturel \u2713 la fonctionnalit\u00e9 \u2713 l'\u00e9l\u00e9gance intemporelle\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/pourquoi-weitzer-parkett\\\/references\\\/privathaus-henriette-salvesen\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/pourquoi-weitzer-parkett\\\/references\\\/privathaus-henriette-salvesen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/pourquoi-weitzer-parkett\\\/references\\\/privathaus-henriette-salvesen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/01_privathaus-salvesen.jpg\",\"contentUrl\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/01_privathaus-salvesen.jpg\",\"width\":1000,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/pourquoi-weitzer-parkett\\\/references\\\/privathaus-henriette-salvesen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9f\u00e9rence\",\"item\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/pourquoi-weitzer-parkett\\\/references\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pavillon Henriette Salvesen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/\",\"name\":\"Weitzer Parkett\",\"description\":\"Intelligente Parkett- und Stiegenl\u00f6sungen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/#organization\",\"name\":\"Weitzer Parkett\",\"url\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/weitzer-parkett-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/weitzer-parkett-logo.png\",\"width\":253,\"height\":81,\"caption\":\"Weitzer Parkett\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/weitzerparkett\",\"https:\\\/\\\/x.com\\\/weitzerparkett\",\"http:\\\/\\\/www.linkedin.com\\\/company\\\/weitzer-parkett\",\"https:\\\/\\\/www.pinterest.com\\\/weitzerparkett\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/weitzerparkett\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pavillon Henriette Salvesen | Weitzer Parkett","description":"Le parquet Weitzer de la maison priv\u00e9e Salvesen allie design scandinave et durabilit\u00e9 : \u2713 le naturel \u2713 la fonctionnalit\u00e9 \u2713 l'\u00e9l\u00e9gance intemporelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/privathaus-henriette-salvesen\/","og_locale":"fr_FR","og_type":"article","og_title":"Pavillon Henriette Salvesen | Weitzer Parkett","og_description":"Le parquet Weitzer de la maison priv\u00e9e Salvesen allie design scandinave et durabilit\u00e9 : \u2713 le naturel \u2713 la fonctionnalit\u00e9 \u2713 l'\u00e9l\u00e9gance intemporelle","og_url":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/privathaus-henriette-salvesen\/","og_site_name":"Weitzer Parkett","article_publisher":"http:\/\/www.facebook.com\/weitzerparkett","article_modified_time":"2025-05-13T11:52:11+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_privathaus-salvesen.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@weitzerparkett","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/privathaus-henriette-salvesen\/","url":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/privathaus-henriette-salvesen\/","name":"Pavillon Henriette Salvesen | Weitzer Parkett","isPartOf":{"@id":"https:\/\/www.weitzer-parkett.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/privathaus-henriette-salvesen\/#primaryimage"},"image":{"@id":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/privathaus-henriette-salvesen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_privathaus-salvesen.jpg","datePublished":"2017-10-10T10:45:18+00:00","dateModified":"2025-05-13T11:52:11+00:00","description":"Le parquet Weitzer de la maison priv\u00e9e Salvesen allie design scandinave et durabilit\u00e9 : \u2713 le naturel \u2713 la fonctionnalit\u00e9 \u2713 l'\u00e9l\u00e9gance intemporelle","breadcrumb":{"@id":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/privathaus-henriette-salvesen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/privathaus-henriette-salvesen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/privathaus-henriette-salvesen\/#primaryimage","url":"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_privathaus-salvesen.jpg","contentUrl":"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2017\/10\/01_privathaus-salvesen.jpg","width":1000,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/privathaus-henriette-salvesen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.weitzer-parkett.com\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e9f\u00e9rence","item":"https:\/\/www.weitzer-parkett.com\/fr\/pourquoi-weitzer-parkett\/references\/"},{"@type":"ListItem","position":3,"name":"Pavillon Henriette Salvesen"}]},{"@type":"WebSite","@id":"https:\/\/www.weitzer-parkett.com\/fr\/#website","url":"https:\/\/www.weitzer-parkett.com\/fr\/","name":"Weitzer Parkett","description":"Intelligente Parkett- und Stiegenl\u00f6sungen","publisher":{"@id":"https:\/\/www.weitzer-parkett.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weitzer-parkett.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.weitzer-parkett.com\/fr\/#organization","name":"Weitzer Parkett","url":"https:\/\/www.weitzer-parkett.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.weitzer-parkett.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2018\/01\/weitzer-parkett-logo.png","contentUrl":"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2018\/01\/weitzer-parkett-logo.png","width":253,"height":81,"caption":"Weitzer Parkett"},"image":{"@id":"https:\/\/www.weitzer-parkett.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/weitzerparkett","https:\/\/x.com\/weitzerparkett","http:\/\/www.linkedin.com\/company\/weitzer-parkett","https:\/\/www.pinterest.com\/weitzerparkett\/","https:\/\/www.youtube.com\/user\/weitzerparkett\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.weitzer-parkett.com\/fr\/wp-json\/wp\/v2\/referenz\/17500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weitzer-parkett.com\/fr\/wp-json\/wp\/v2\/referenz"}],"about":[{"href":"https:\/\/www.weitzer-parkett.com\/fr\/wp-json\/wp\/v2\/types\/referenz"}],"author":[{"embeddable":true,"href":"https:\/\/www.weitzer-parkett.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weitzer-parkett.com\/fr\/wp-json\/wp\/v2\/comments?post=17500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weitzer-parkett.com\/fr\/wp-json\/wp\/v2\/media\/5576"}],"wp:attachment":[{"href":"https:\/\/www.weitzer-parkett.com\/fr\/wp-json\/wp\/v2\/media?parent=17500"}],"wp:term":[{"taxonomy":"reference_category","embeddable":true,"href":"https:\/\/www.weitzer-parkett.com\/fr\/wp-json\/wp\/v2\/reference_category?post=17500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}