{"id":60653,"date":"2024-04-29T14:06:26","date_gmt":"2024-04-29T12:06:26","guid":{"rendered":"https:\/\/www.weitzer-parkett.com\/?page_id=60653"},"modified":"2024-05-21T09:53:52","modified_gmt":"2024-05-21T07:53:52","slug":"sustainable-development-goals","status":"publish","type":"page","link":"https:\/\/www.weitzer-parkett.com\/en\/sustainability\/sustainable-development-goals\/","title":{"rendered":"Sustainable Development Goals"},"content":{"rendered":"<div id=\"ep-block-page-header-block_9bd3f19571ab856fe0d0ccbcb5beb129\" class=\"ep-block-page-header ep-block  chosen-bg-theme-beige type-2\">\n            <div class=\"show-frontend\">\n\n            \n                <div class=\"inner\">\n                    <div class=\"container mx-auto\">\n                        <div class=\"text-container\">\n\n                                                            <div class=\"breadcrumbs-wrapper\">\n                                    <span><span><a href=\"https:\/\/www.weitzer-parkett.com\/en\/\">Home<\/a><\/span><\/span>\n                                <\/div>\n                            \n                                                            <h1>Sustainable Development Goals<\/h1>\n                            \n                                                            <div class=\"text-wrapper\"><p><strong>Taking responsibility together<\/strong><\/p>\n<\/div>\n                            \n                                                            <div class=\"btn-wrapper\">\n                                                                            <div class=\"link\">\n                                            <a href=\"https:\/\/www.weitzer-parkett.com\/en\/sustainability\/measures\/\" title=\"Our measures for more sustainability\" target=\"\" class=\"btn arrow-right\">\n                                                Our measures for more sustainability\n                                            <\/a>\n                                        <\/div>\n                                    \n                                                                            <div class=\"link\">\n                                            <a href=\"https:\/\/www.weitzer-parkett.com\/en\/sustainability\/\" title=\"Discover Weitzer sustainability\" target=\"\" class=\"btn link arrow-right\">\n                                                Discover Weitzer sustainability\n                                            <\/a>\n                                        <\/div>\n                                                                    <\/div>\n                            \n                        <\/div>\n                    <\/div>\n                <\/div>\n\n                                                        <div class=\"image-wrapper\">\n                        \n                        \n                        \n                                                                                                        \n                        \n                                                                        \n                        <picture class=\"image\">\n                            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/04\/SDGs-nachhaltigkeit-weitzer-parkett-910x666-c-center.jpg 1x\" media=\"(min-resolution: 120dpi)\"\/>\n                            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/04\/SDGs-nachhaltigkeit-weitzer-parkett-910x666-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n                            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/04\/SDGs-nachhaltigkeit-weitzer-parkett-684x496-c-center.jpg 1x\" media=\"(min-width: 768px)\"\/>\n                            <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/04\/SDGs-nachhaltigkeit-weitzer-parkett-356x258-c-center.jpg 1x\" media=\"(max-width: 767px)\"\/>\n                            <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/04\/SDGs-nachhaltigkeit-weitzer-parkett-356x258-c-center.jpg\" alt=\"\" title=\"SDGs-nachhaltigkeit-weitzer-parkett\"\/>\n                        <\/picture>\n                    <\/div>\n\n                                    \n                    <\/div>\n    <\/div>\n\n\n<div id=\"ep-block-pre-text-block_e79f07b02dbc420f37e1aeb70becbaf4\" class=\"ep-block-pre-text ep-block  chosen-\">\n                        <div class=\"show-frontend\">\n                <div class=\"inner\">\n                    <div class=\"holder\"><p>At Weitzer Parkett, we are passionate about integrating the 17 United Nations Sustainable Development Goals into our daily operations. Learn more about our efforts to make a measurable contribution to a sustainable and just world by 2030.<\/p>\n<\/div>\n                <\/div>\n            <\/div>\n            <\/div>\n\n<div id=\"ep-block-wysiwyg-block_432262579e6d0a19b84f1dcae6957d63\" class=\"ep-block-wysiwyg ep-block  chosen-\">\n                        <div class=\"show-frontend\">\n                <div class=\"inner\">\n                    <div class=\"holder\"><h2>17 United Nations objectives<\/h2>\n<p>Our sustainable actions bear witness to our ongoing efforts to integrate the 17 United Nations Sustainable Development Goals into our corporate practice. We are constantly working to anchor these goals in our daily operations and to make continuous progress. Our company is determined to contribute to a measurable contribution to a sustainable and just world by 2030.<\/p>\n<\/div>\n                <\/div>\n            <\/div>\n            <\/div>\n\n<div id=\"ep-block-spacer-block_0f8250616e1ee396122c19b654a5189c\" class=\"ep-block-spacer ep-block  chosen-\">\n            <div class=\"show-frontend\">\n                        <style>\n                #ep-spacer-FRXrZ {\n                    height: 100px;\n                }\n                @media (max-width: 767px) {\n                    #ep-spacer-FRXrZ {\n                        height: 40px;\n                    }\n                }\n                @media (min-width: 768px) and (max-width: 1023px) {\n                    #ep-spacer-FRXrZ {\n                        height: 60px;\n                    }\n                }\n            <\/style>\n            <div id=\"ep-spacer-FRXrZ\"><\/div>\n        <\/div>\n    <\/div>\n\n<div id=\"ep-block-title-subtitle-block_f397590d9e5052858daed24938a861d3\" class=\"ep-block-title-subtitle ep-block  chosen-bg-white\">\n            <div class=\"show-frontend\">\n            <div class=\"inner\">\n                <div class=\"holder content-text-center\">\n\n                    \n                    \n                                            <div class=\"title\">\n                            <h3 class=\"  font-weight- headline font-normal\">Curious which of the SDGs are already firmly anchored in our fields of action?<\/h3>\n                        <\/div>\n                    \n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n\n<div id=\"ep-block-teaser-block_0f23328c4b7f1f192440b251c0950ca0\" class=\"ep-block-teaser ep-block  chosen-bg-white\">\n            <div class=\"show-frontend style-2\">\n            <div class=\"rectangle rectangle-1\"><\/div>\n            <div class=\"rectangle rectangle-2\"><\/div>\n            <div class=\"holder\">\n\n                                                                                                        \n                <div class=\"position-wrapper\">\n                                                                                                                                                                    <div class=\"image-wrapper\">                             <picture>\n                                <source srcset=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/05\/en_SDGs-content-nachhaltigkeit-weitzer-parkett-582x388-c-center.jpg 1x\" media=\"(min-width: 1024px)\"\/>\n                                                                 <a href=\"https:\/\/www.weitzer-parkett.com\/en\/sustainability\/sustainable-development-goals\/#ep_flip_61725_36\" target=\"\">\n                                <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/05\/en_SDGs-content-nachhaltigkeit-weitzer-parkett-582x388-c-center.jpg\" alt=\"\" title=\"en_SDGs-content-nachhaltigkeit-weitzer-parkett\"\/>\n                                <\/a>\n                            <\/picture>\n                        <\/div>\n                    \n                    <div class=\"text-wrapper\">\n                        \n                                                    <div class=\"text\"><p>In our Sustainability Report, we reflect not only on our progress in conserving resources and acting sustainably, but also on our social responsibility and commitment to a positive corporate culture.<\/p>\n<p>Our goal is not only to produce high-quality wooden floors, but to do so in a way that protects our environment and improves the quality of life of our community.<\/p>\n<\/div>\n                        \n                                                    <div class=\"link-wrapper\">\n                                <a href=\"https:\/\/www.weitzer-parkett.com\/en\/sustainability\/sustainable-development-goals\/#ep_flip_61725_36\" target=\"\" class=\"btn ghost\">\n                                    To the sustainability report\n                                <\/a>\n                            <\/div>\n                        \n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div id=\"ep-block-spacer-block_05a88f8060bb0466485fcbef2fefe62b\" class=\"ep-block-spacer ep-block  chosen-bg-white\">\n            <div class=\"show-frontend\">\n                        <style>\n                #ep-spacer-QUejz {\n                    height: 100px;\n                }\n                @media (max-width: 767px) {\n                    #ep-spacer-QUejz {\n                        height: 40px;\n                    }\n                }\n                @media (min-width: 768px) and (max-width: 1023px) {\n                    #ep-spacer-QUejz {\n                        height: 60px;\n                    }\n                }\n            <\/style>\n            <div id=\"ep-spacer-QUejz\"><\/div>\n        <\/div>\n    <\/div>\n\n<div id=\"ep-block-title-subtitle-block_8b0c0a93cffff810dfc17420d6b5addc\" class=\"ep-block-title-subtitle ep-block  chosen-\">\n            <div class=\"show-frontend\">\n            <div class=\"inner\">\n                <div class=\"holder content-text-center\">\n\n                    \n                                            <div class=\"sub-title\">\n                                                        \n                            <h6 class=\"\">Sustainable Development Goals<\/h6>\n                        <\/div>\n                    \n                                            <div class=\"title\">\n                            <h2 class=\"  font-weight- headline font-normal\">Our focus<\/h2>\n                        <\/div>\n                    \n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n\n<div id=\"ep-block-development-goals-block_aed5e45acd7178ec49dc4a87d1a26633\" class=\"ep-block-development-goals ep-block  chosen-\">\n                        <div class=\"show-frontend\">\n                <div class=\"inner\">\n                    <div class=\"goals-wrapper\">\n                                                    <div class=\"goal\" style=\"background-color: #47a439\">\n                                <div class=\"goal-inner\">\n                                    <div class=\"goal-top\">\n                                        <div class=\"goal-no\">1<\/div>\n                                        <h4 class=\"goal-title\">Good health &#038; well-being<\/h4>\n                                    <\/div>\n                                                                            <div class=\"goal-image\">\n                                                                                                                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/04\/gesundheit-wohlergehen.png\" alt=\"\" title=\"gesundheit-wohlergehen\"\/>\n                                                                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                                                    <div class=\"goal\" style=\"background-color: #c61c2d\">\n                                <div class=\"goal-inner\">\n                                    <div class=\"goal-top\">\n                                        <div class=\"goal-no\">2<\/div>\n                                        <h4 class=\"goal-title\">Quality education<\/h4>\n                                    <\/div>\n                                                                            <div class=\"goal-image\">\n                                                                                                                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/04\/hochwertige-bildung.png\" alt=\"\" title=\"hochwertige-bildung\"\/>\n                                                                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                                                    <div class=\"goal\" style=\"background-color: #ef3029\">\n                                <div class=\"goal-inner\">\n                                    <div class=\"goal-top\">\n                                        <div class=\"goal-no\">3<\/div>\n                                        <h4 class=\"goal-title\">Gender equality<\/h4>\n                                    <\/div>\n                                                                            <div class=\"goal-image\">\n                                                                                                                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/04\/geschlechtergleichheit.png\" alt=\"\" title=\"geschlechtergleichheit\"\/>\n                                                                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                                                    <div class=\"goal\" style=\"background-color: #55c4e6\">\n                                <div class=\"goal-inner\">\n                                    <div class=\"goal-top\">\n                                        <div class=\"goal-no\">4<\/div>\n                                        <h4 class=\"goal-title\">Clean water &#038; sanitation<\/h4>\n                                    <\/div>\n                                                                            <div class=\"goal-image\">\n                                                                                                                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/04\/sauberes-wasser-sanitaereinrichtungen.png\" alt=\"\" title=\"sauberes-wasser-sanitaereinrichtungen\"\/>\n                                                                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                                                    <div class=\"goal\" style=\"background-color: #f7bf0b\">\n                                <div class=\"goal-inner\">\n                                    <div class=\"goal-top\">\n                                        <div class=\"goal-no\">5<\/div>\n                                        <h4 class=\"goal-title\">Affordable &#038; clean energy<\/h4>\n                                    <\/div>\n                                                                            <div class=\"goal-image\">\n                                                                                                                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/04\/bezahlbare-saubere-energie.png\" alt=\"\" title=\"bezahlbare-saubere-energie\"\/>\n                                                                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                                                    <div class=\"goal\" style=\"background-color: #a11640\">\n                                <div class=\"goal-inner\">\n                                    <div class=\"goal-top\">\n                                        <div class=\"goal-no\">6<\/div>\n                                        <h4 class=\"goal-title\">Decent work &#038; economic growth<\/h4>\n                                    <\/div>\n                                                                            <div class=\"goal-image\">\n                                                                                                                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/04\/menschenwuerdige-arbeit-wirtschaftswachstum.png\" alt=\"\" title=\"menschenwuerdige-arbeit-wirtschaftswachstum\"\/>\n                                                                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                                                    <div class=\"goal\" style=\"background-color: #f25524\">\n                                <div class=\"goal-inner\">\n                                    <div class=\"goal-top\">\n                                        <div class=\"goal-no\">7<\/div>\n                                        <h4 class=\"goal-title\">Industry, innovation &#038; infrastructure<\/h4>\n                                    <\/div>\n                                                                            <div class=\"goal-image\">\n                                                                                                                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/04\/industrie-innovation-infrastruktur.png\" alt=\"\" title=\"industrie-innovation-infrastruktur\"\/>\n                                                                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                                                    <div class=\"goal\" style=\"background-color: #ba861c\">\n                                <div class=\"goal-inner\">\n                                    <div class=\"goal-top\">\n                                        <div class=\"goal-no\">8<\/div>\n                                        <h4 class=\"goal-title\">Responsible consumption &#038; production<\/h4>\n                                    <\/div>\n                                                                            <div class=\"goal-image\">\n                                                                                                                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/04\/nachhaltiger-konsum-produktion.png\" alt=\"\" title=\"nachhaltiger-konsum-produktion\"\/>\n                                                                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                                                    <div class=\"goal\" style=\"background-color: #3c7f3e\">\n                                <div class=\"goal-inner\">\n                                    <div class=\"goal-top\">\n                                        <div class=\"goal-no\">9<\/div>\n                                        <h4 class=\"goal-title\">Climate action<\/h4>\n                                    <\/div>\n                                                                            <div class=\"goal-image\">\n                                                                                                                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/04\/massnahmen-zum-klimaschutz.png\" alt=\"\" title=\"massnahmen-zum-klimaschutz\"\/>\n                                                                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                                                    <div class=\"goal\" style=\"background-color: #55bf35\">\n                                <div class=\"goal-inner\">\n                                    <div class=\"goal-top\">\n                                        <div class=\"goal-no\">10<\/div>\n                                        <h4 class=\"goal-title\">Life on land<\/h4>\n                                    <\/div>\n                                                                            <div class=\"goal-image\">\n                                                                                                                                        <img decoding=\"async\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/04\/leben-an-land.png\" alt=\"\" title=\"leben-an-land\"\/>\n                                                                                    <\/div>\n                                                                    <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n            <\/div>\n\n<div id=\"ep-block-spacer-block_05a88f8060bb0466485fcbef2fefe62b\" class=\"ep-block-spacer ep-block  chosen-bg-white\">\n            <div class=\"show-frontend\">\n                        <style>\n                #ep-spacer-ofRId {\n                    height: 100px;\n                }\n                @media (max-width: 767px) {\n                    #ep-spacer-ofRId {\n                        height: 40px;\n                    }\n                }\n                @media (min-width: 768px) and (max-width: 1023px) {\n                    #ep-spacer-ofRId {\n                        height: 60px;\n                    }\n                }\n            <\/style>\n            <div id=\"ep-spacer-ofRId\"><\/div>\n        <\/div>\n    <\/div>\n\n<div id=\"ep-block-spacer-block_bb535585d8ebefba60492d47d86df8d4\" class=\"ep-block-spacer ep-block  chosen-bg-theme-beige\">\n            <div class=\"show-frontend\">\n                        <style>\n                #ep-spacer-fZLsq {\n                    height: 100px;\n                }\n                @media (max-width: 767px) {\n                    #ep-spacer-fZLsq {\n                        height: 40px;\n                    }\n                }\n                @media (min-width: 768px) and (max-width: 1023px) {\n                    #ep-spacer-fZLsq {\n                        height: 60px;\n                    }\n                }\n            <\/style>\n            <div id=\"ep-spacer-fZLsq\"><\/div>\n        <\/div>\n    <\/div>\n\n<div id=\"ep-block-title-subtitle-block_6395cda8b0bc443431cbde99025d1bf2\" class=\"ep-block-title-subtitle ep-block  chosen-bg-theme-beige\">\n            <div class=\"show-frontend\">\n            <div class=\"inner\">\n                <div class=\"holder content-text-center\">\n\n                    \n                    \n                                            <div class=\"title\">\n                            <h3 class=\" h3 font-weight- headline font-normal\"><h3 id=\"nachhaltigkeitsbericht\">Browse through our sustainability report<\/h3><\/h3>\n                        <\/div>\n                    \n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n\n<div id=\"ep-block-wysiwyg-block_ddd4c0dd73047abcbe0330030ad4896e\" class=\"ep-block-wysiwyg ep-block  chosen-bg-theme-beige\">\n                        <div class=\"show-frontend\">\n                <div class=\"inner\">\n                    <div class=\"holder\">\n        <div class=\"ep-flip\">\n            <script class=\"ep-flip-data\" type=\"application\/json\">{\"pdfUrl\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/77957_en_WGroup_NHB2024_RZ_200dpi-compressed.pdf\",\"lightBox\":true,\"lightboxBackground\":\"\",\"pageRoughness\":\".5\",\"lightIntensity\":\".6\",\"lightPositionY\":\"400\",\"shadowOpacity\":\".5\",\"skin\":\"dark\",\"deeplinkingPrefix\":\"ep_flip_61725_\",\"btnDownloadPages\":{\"enabled\":true},\"btnDownloadPdf\":{\"enabled\":true},\"btnShare\":{\"enabled\":true},\"btnPrint\":{\"enabled\":true},\"btnExpand\":{\"enabled\":true},\"btnBookmark\":{\"enabled\":true},\"strings\":{\"print\":\"Print\",\"printLeftPage\":\"Print left page\",\"printRightPage\":\"Print right page\",\"printCurrentPage\":\"Print current page\",\"printAllPages\":\"Print all pages\",\"download\":\"Download\",\"downloadLeftPage\":\"Download left page\",\"downloadRightPage\":\"Download right page\",\"downloadCurrentPage\":\"Download current page\",\"downloadAllPages\":\"Download all pages\",\"bookmarks\":\"Bookmarks\",\"bookmarkLeftPage\":\"Bookmark left page\",\"bookmarkRightPage\":\"Bookmark right page\",\"bookmarkCurrentPage\":\"Bookmark current page\",\"search\":\"Search\",\"findInDocument\":\"Find in document\",\"pagesFoundContaining\":\"pages found containing\",\"thumbnails\":\"Thumbnails\",\"tableOfContent\":\"Table of content\",\"share\":\"Share\",\"pressEscToClose\":\"Press ESC to close\"},\"assets\":{\"preloader\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/wp-content\\\/plugins\\\/ep-flip\\\/public\\\/assets\\\/images\\\/flip\\\/preloader.jpg\",\"overlay\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/wp-content\\\/plugins\\\/ep-flip\\\/public\\\/assets\\\/images\\\/flip\\\/images\\\/overlay.png\",\"flipMp3\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/wp-content\\\/plugins\\\/ep-flip\\\/public\\\/assets\\\/mp3\\\/turnPage.mp3\",\"spinner\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/wp-content\\\/plugins\\\/ep-flip\\\/public\\\/assets\\\/images\\\/flip\\\/spinner.gif\",\"backgroundMp3\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/wp-content\\\/plugins\\\/ep-flip\\\/public\\\/assets\\\/mp3\\\/background.mp3\"}}<\/script>\n            <div class=\"ep-flip-element\"><img decoding=\"async\" width=\"2000\" height=\"1500\" src=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/05\/nachhaltigkeitsbericht-magazin-2025-en.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/05\/nachhaltigkeitsbericht-magazin-2025-en.jpg 2000w, \/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/05\/nachhaltigkeitsbericht-magazin-2025-en-250x188.jpg 250w, \/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/05\/nachhaltigkeitsbericht-magazin-2025-en-700x525.jpg 700w, \/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/05\/nachhaltigkeitsbericht-magazin-2025-en-768x576.jpg 768w, \/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/05\/nachhaltigkeitsbericht-magazin-2025-en-1536x1152.jpg 1536w, \/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/05\/nachhaltigkeitsbericht-magazin-2025-en-120x90.jpg 120w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/div>\n        <\/div>\n<\/div>\n                <\/div>\n            <\/div>\n            <\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":60592,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-60653","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sustainable Development Goals | Weitzer Parkett<\/title>\n<meta name=\"description\" content=\"Taking responsibility together. Learn more about our efforts to make a measurable contribution to a sustainable and just world by 2030.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sustainable Development Goals | Weitzer Parkett\" \/>\n<meta property=\"og:description\" content=\"Taking responsibility together. Learn more about our efforts to make a measurable contribution to a sustainable and just world by 2030.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weitzer-parkett.com\/en\/sustainability\/sustainable-development-goals\/\" \/>\n<meta property=\"og:site_name\" content=\"Weitzer Parkett\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/weitzerparkett\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-21T07:53:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/04\/SDGs-content-nachhaltigkeit-weitzer-parkett.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1956\" \/>\n\t<meta property=\"og:image:height\" content=\"1196\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@weitzerparkett\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/en\\\/sustainability\\\/sustainable-development-goals\\\/\",\"url\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/en\\\/sustainability\\\/sustainable-development-goals\\\/\",\"name\":\"Sustainable Development Goals | Weitzer Parkett\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/en\\\/#website\"},\"datePublished\":\"2024-04-29T12:06:26+00:00\",\"dateModified\":\"2024-05-21T07:53:52+00:00\",\"description\":\"Taking responsibility together. Learn more about our efforts to make a measurable contribution to a sustainable and just world by 2030.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/en\\\/sustainability\\\/sustainable-development-goals\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weitzer-parkett.com\\\/en\\\/sustainability\\\/sustainable-development-goals\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/en\\\/sustainability\\\/sustainable-development-goals\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sustainability\",\"item\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/en\\\/sustainability\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sustainable Development Goals\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/en\\\/\",\"name\":\"Weitzer Parkett\",\"description\":\"Intelligente Parkett- und Stiegenl\u00f6sungen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/en\\\/#organization\",\"name\":\"Weitzer Parkett\",\"url\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/weitzer-parkett-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/weitzer-parkett-logo.png\",\"width\":253,\"height\":81,\"caption\":\"Weitzer Parkett\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weitzer-parkett.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/weitzerparkett\",\"https:\\\/\\\/x.com\\\/weitzerparkett\",\"http:\\\/\\\/www.linkedin.com\\\/company\\\/weitzer-parkett\",\"https:\\\/\\\/www.pinterest.com\\\/weitzerparkett\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/weitzerparkett\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sustainable Development Goals | Weitzer Parkett","description":"Taking responsibility together. Learn more about our efforts to make a measurable contribution to a sustainable and just world by 2030.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"en_US","og_type":"article","og_title":"Sustainable Development Goals | Weitzer Parkett","og_description":"Taking responsibility together. Learn more about our efforts to make a measurable contribution to a sustainable and just world by 2030.","og_url":"https:\/\/www.weitzer-parkett.com\/en\/sustainability\/sustainable-development-goals\/","og_site_name":"Weitzer Parkett","article_publisher":"http:\/\/www.facebook.com\/weitzerparkett","article_modified_time":"2024-05-21T07:53:52+00:00","og_image":[{"width":1956,"height":1196,"url":"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2024\/04\/SDGs-content-nachhaltigkeit-weitzer-parkett.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@weitzerparkett","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.weitzer-parkett.com\/en\/sustainability\/sustainable-development-goals\/","url":"https:\/\/www.weitzer-parkett.com\/en\/sustainability\/sustainable-development-goals\/","name":"Sustainable Development Goals | Weitzer Parkett","isPartOf":{"@id":"https:\/\/www.weitzer-parkett.com\/en\/#website"},"datePublished":"2024-04-29T12:06:26+00:00","dateModified":"2024-05-21T07:53:52+00:00","description":"Taking responsibility together. Learn more about our efforts to make a measurable contribution to a sustainable and just world by 2030.","breadcrumb":{"@id":"https:\/\/www.weitzer-parkett.com\/en\/sustainability\/sustainable-development-goals\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weitzer-parkett.com\/en\/sustainability\/sustainable-development-goals\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.weitzer-parkett.com\/en\/sustainability\/sustainable-development-goals\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.weitzer-parkett.com\/en\/"},{"@type":"ListItem","position":2,"name":"Sustainability","item":"https:\/\/www.weitzer-parkett.com\/en\/sustainability\/"},{"@type":"ListItem","position":3,"name":"Sustainable Development Goals"}]},{"@type":"WebSite","@id":"https:\/\/www.weitzer-parkett.com\/en\/#website","url":"https:\/\/www.weitzer-parkett.com\/en\/","name":"Weitzer Parkett","description":"Intelligente Parkett- und Stiegenl\u00f6sungen","publisher":{"@id":"https:\/\/www.weitzer-parkett.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weitzer-parkett.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.weitzer-parkett.com\/en\/#organization","name":"Weitzer Parkett","url":"https:\/\/www.weitzer-parkett.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.weitzer-parkett.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2018\/01\/weitzer-parkett-logo.png","contentUrl":"https:\/\/www.weitzer-parkett.com\/wp-content\/uploads\/2018\/01\/weitzer-parkett-logo.png","width":253,"height":81,"caption":"Weitzer Parkett"},"image":{"@id":"https:\/\/www.weitzer-parkett.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/weitzerparkett","https:\/\/x.com\/weitzerparkett","http:\/\/www.linkedin.com\/company\/weitzer-parkett","https:\/\/www.pinterest.com\/weitzerparkett\/","https:\/\/www.youtube.com\/user\/weitzerparkett\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.weitzer-parkett.com\/en\/wp-json\/wp\/v2\/pages\/60653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weitzer-parkett.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.weitzer-parkett.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.weitzer-parkett.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weitzer-parkett.com\/en\/wp-json\/wp\/v2\/comments?post=60653"}],"version-history":[{"count":5,"href":"https:\/\/www.weitzer-parkett.com\/en\/wp-json\/wp\/v2\/pages\/60653\/revisions"}],"predecessor-version":[{"id":61729,"href":"https:\/\/www.weitzer-parkett.com\/en\/wp-json\/wp\/v2\/pages\/60653\/revisions\/61729"}],"up":[{"embeddable":true,"href":"https:\/\/www.weitzer-parkett.com\/en\/wp-json\/wp\/v2\/pages\/60592"}],"wp:attachment":[{"href":"https:\/\/www.weitzer-parkett.com\/en\/wp-json\/wp\/v2\/media?parent=60653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}